{"id":563,"date":"2017-03-12T14:58:51","date_gmt":"2017-03-12T13:58:51","guid":{"rendered":"http:\/\/tus.eschringen.de\/wordpress\/?post_type=tribe_events&#038;p=563"},"modified":"2017-04-23T17:47:17","modified_gmt":"2017-04-23T15:47:17","slug":"tus-eschringen-sv-scheidt","status":"publish","type":"tribe_events","link":"https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/","title":{"rendered":"TuS Eschringen  &#8211; SV Scheidt"},"content":{"rendered":"<p><strong>Kreisliga A Halberg<\/strong><\/p>\n<p>26. Spieltag<\/p>\n<p>TuS Eschringen \u2013 SV Scheidt <span style=\"color: #ff0000;\"><strong>3:0 <\/strong><\/span>(2:0)<\/p>\n<p><strong>Torsch\u00fctzen:<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>1:0<\/strong> <\/span>Eigentor (2. Min)<br \/>\n<span style=\"color: #ff0000;\"><strong>2:0<\/strong> <\/span>Florian Hoffmann (44. Min)<br \/>\n<span style=\"color: #ff0000;\"><strong>3:0<\/strong><\/span> Philipp Wilhelm (77.Min)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kreisliga A Halberg 26. Spieltag TuS Eschringen \u2013 SV Scheidt 3:0 (2:0) Torsch\u00fctzen: 1:0 Eigentor (2. Min) 2:0 Florian Hoffmann (44. Min) 3:0 Philipp Wilhelm (77.Min)<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"generate_page_header":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[5],"class_list":["post-563","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-kreisliga-a-halberg","cat_kreisliga-a-halberg"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TuS Eschringen - SV Scheidt - TuS Eschringen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TuS Eschringen - SV Scheidt - TuS Eschringen\" \/>\n<meta property=\"og:description\" content=\"Kreisliga A Halberg 26. Spieltag TuS Eschringen \u2013 SV Scheidt 3:0 (2:0) Torsch\u00fctzen: 1:0 Eigentor (2. Min) 2:0 Florian Hoffmann (44. Min) 3:0 Philipp Wilhelm (77.Min)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/\" \/>\n<meta property=\"og:site_name\" content=\"TuS Eschringen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TuS.Eschringen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-23T15:47:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/event\\\/tus-eschringen-sv-scheidt\\\/\",\"url\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/event\\\/tus-eschringen-sv-scheidt\\\/\",\"name\":\"TuS Eschringen - SV Scheidt - TuS Eschringen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/#website\"},\"datePublished\":\"2017-03-12T13:58:51+00:00\",\"dateModified\":\"2017-04-23T15:47:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/event\\\/tus-eschringen-sv-scheidt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/event\\\/tus-eschringen-sv-scheidt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/event\\\/tus-eschringen-sv-scheidt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TuS Eschringen &#8211; SV Scheidt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/\",\"name\":\"TuS Eschringen\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/#organization\",\"name\":\"TuS Eschringen\",\"url\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/tus.eschringen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Web_kopf.jpg?fit=1260%2C240&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/tus.eschringen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Web_kopf.jpg?fit=1260%2C240&ssl=1\",\"width\":1260,\"height\":240,\"caption\":\"TuS Eschringen\"},\"image\":{\"@id\":\"https:\\\/\\\/tus.eschringen.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TuS.Eschringen\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tus.eschringen\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TuS Eschringen - SV Scheidt - TuS Eschringen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/","og_locale":"de_DE","og_type":"article","og_title":"TuS Eschringen - SV Scheidt - TuS Eschringen","og_description":"Kreisliga A Halberg 26. Spieltag TuS Eschringen \u2013 SV Scheidt 3:0 (2:0) Torsch\u00fctzen: 1:0 Eigentor (2. Min) 2:0 Florian Hoffmann (44. Min) 3:0 Philipp Wilhelm (77.Min)","og_url":"https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/","og_site_name":"TuS Eschringen","article_publisher":"https:\/\/www.facebook.com\/TuS.Eschringen\/","article_modified_time":"2017-04-23T15:47:17+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/","url":"https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/","name":"TuS Eschringen - SV Scheidt - TuS Eschringen","isPartOf":{"@id":"https:\/\/tus.eschringen.de\/wordpress\/#website"},"datePublished":"2017-03-12T13:58:51+00:00","dateModified":"2017-04-23T15:47:17+00:00","breadcrumb":{"@id":"https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tus.eschringen.de\/wordpress\/event\/tus-eschringen-sv-scheidt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tus.eschringen.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/tus.eschringen.de\/wordpress\/events\/"},{"@type":"ListItem","position":3,"name":"TuS Eschringen &#8211; SV Scheidt"}]},{"@type":"WebSite","@id":"https:\/\/tus.eschringen.de\/wordpress\/#website","url":"https:\/\/tus.eschringen.de\/wordpress\/","name":"TuS Eschringen","description":"","publisher":{"@id":"https:\/\/tus.eschringen.de\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tus.eschringen.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tus.eschringen.de\/wordpress\/#organization","name":"TuS Eschringen","url":"https:\/\/tus.eschringen.de\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tus.eschringen.de\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/tus.eschringen.de\/wordpress\/wp-content\/uploads\/2025\/07\/Web_kopf.jpg?fit=1260%2C240&ssl=1","contentUrl":"https:\/\/i0.wp.com\/tus.eschringen.de\/wordpress\/wp-content\/uploads\/2025\/07\/Web_kopf.jpg?fit=1260%2C240&ssl=1","width":1260,"height":240,"caption":"TuS Eschringen"},"image":{"@id":"https:\/\/tus.eschringen.de\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TuS.Eschringen\/","https:\/\/www.instagram.com\/tus.eschringen\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tus.eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events\/563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tus.eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/tus.eschringen.de\/wordpress\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/tus.eschringen.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":3,"href":"https:\/\/tus.eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events\/563\/revisions"}],"predecessor-version":[{"id":629,"href":"https:\/\/tus.eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events\/563\/revisions\/629"}],"wp:attachment":[{"href":"https:\/\/tus.eschringen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=563"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tus.eschringen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=563"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/tus.eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events_cat?post=563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}